{"id":10008,"date":"2021-10-11T19:30:09","date_gmt":"2021-10-11T19:30:09","guid":{"rendered":"https:\/\/techmastermx.ddns.net\/producto\/juegos-de-servicio-diesel-4\/"},"modified":"2023-09-04T17:25:38","modified_gmt":"2023-09-05T00:25:38","slug":"juegos-de-servicio-diesel-4","status":"publish","type":"product","link":"https:\/\/techmasterdemexico.com\/es\/producto\/juegos-de-servicio-diesel-4\/","title":{"rendered":"Juegos de servicio diesel"},"content":{"rendered":"<ul>\n<li>Dise\u00f1o de pared delgada para un mejor acceso alrededor de obst\u00e1culos<\/li>\n<li>Uso en conductos de direcci\u00f3n asistida, v\u00e1lvulas de expansi\u00f3n, conductos de aire acondicionado, conductos hidr\u00e1ulicos y conductos de equipos industriales y filtros de combustible<\/li>\n<li>Las llaves de vaso Snap-on\u00ae con sistema Flank Drive\u00ae sujetan la fijaci\u00f3n por los flancos\/planos, lo que proporciona un 15-25% m\u00e1s de fuerza de giro<\/li>\n<li>El acabado de aleaci\u00f3n de n\u00edquel-cromo resiste el \u00f3xido y la corrosi\u00f3n<\/li>\n<li>Fabricadas con acero patentado de la m\u00e1s alta calidad, que proporciona una resistencia y durabilidad \u00f3ptimas<\/li>\n<li>Configuraci\u00f3n de 6 puntas y sistema de apriete Flank Drive<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Par de apriete m\u00e1ximo recomendado: 930 in-lb<br \/>\nDimensi\u00f3n E, profundidad de la cabeza, mm 12,7<br \/>\nTama\u00f1o de accionamiento, pulgadas 3\/8<br \/>\nDimensi\u00f3n A, O.D., mm 33.3<br \/>\nASME\u00ae B107.21<br \/>\nPa\u00eds de origen EE.UU.<br \/>\nDimensi\u00f3n B, Apertura de pared, mm 14,7<br \/>\nTama\u00f1o, mm 19<br \/>\nDimensi\u00f3n C, de centro a centro, mm 20,6<br \/>\nDimensi\u00f3n D, longitud, mm 44,7<br \/>\nAcabado Cromado<br \/>\nPar de apriete m\u00e1ximo recomendado, in-lb 740<br \/>\nEstilo de 6 puntos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dise\u00f1o de pared delgada para un mejor acceso alrededor de obst\u00e1culos Uso en conductos de direcci\u00f3n asistida, v\u00e1lvulas de expansi\u00f3n, conductos de aire acondicionado, conductos hidr\u00e1ulicos y conductos de equipos industriales y filtros de combustible Las llaves de vaso Snap-on\u00ae con sistema Flank Drive\u00ae sujetan la fijaci\u00f3n por los flancos\/planos, lo que proporciona un 15-25% [&hellip;]<\/p>\n","protected":false},"featured_media":20623,"template":"","meta":{"_acf_changed":false},"pwb-brand":[98],"product_brand":[],"product_cat":[366,290,287,48],"product_tag":[],"class_list":["post-10008","product","type-product","status-publish","has-post-thumbnail","pwb-brand-snap-on","product_cat-todos-los-productos","product_cat-herramientas-diesel","product_cat-herramientas-manuales-generales","product_cat-snap-on","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juegos de servicio diesel - Techmaster de Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/techmasterdemexico.com\/es\/producto\/juegos-de-servicio-diesel-4\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juegos de servicio diesel - Techmaster de Mexico\" \/>\n<meta property=\"og:description\" content=\"Dise\u00f1o de pared delgada para un mejor acceso alrededor de obst\u00e1culos Uso en conductos de direcci\u00f3n asistida, v\u00e1lvulas de expansi\u00f3n, conductos de aire acondicionado, conductos hidr\u00e1ulicos y conductos de equipos industriales y filtros de combustible Las llaves de vaso Snap-on\u00ae con sistema Flank Drive\u00ae sujetan la fijaci\u00f3n por los flancos\/planos, lo que proporciona un 15-25% [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/techmasterdemexico.com\/es\/producto\/juegos-de-servicio-diesel-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Techmaster de Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T00:25:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/snap-on-FRHM19.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/juegos-de-servicio-diesel-4\\\/\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/juegos-de-servicio-diesel-4\\\/\",\"name\":\"Juegos de servicio diesel - Techmaster de Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/juegos-de-servicio-diesel-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/juegos-de-servicio-diesel-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/snap-on-FRHM19.png\",\"datePublished\":\"2021-10-11T19:30:09+00:00\",\"dateModified\":\"2023-09-05T00:25:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/juegos-de-servicio-diesel-4\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/juegos-de-servicio-diesel-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/juegos-de-servicio-diesel-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/snap-on-FRHM19.png\",\"contentUrl\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/snap-on-FRHM19.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/juegos-de-servicio-diesel-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/techmasterdemexico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juegos de servicio diesel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/es\\\/\",\"name\":\"Techmaster de Mexico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/techmasterdemexico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juegos de servicio diesel - Techmaster de Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/techmasterdemexico.com\/es\/producto\/juegos-de-servicio-diesel-4\/","og_locale":"es_MX","og_type":"article","og_title":"Juegos de servicio diesel - Techmaster de Mexico","og_description":"Dise\u00f1o de pared delgada para un mejor acceso alrededor de obst\u00e1culos Uso en conductos de direcci\u00f3n asistida, v\u00e1lvulas de expansi\u00f3n, conductos de aire acondicionado, conductos hidr\u00e1ulicos y conductos de equipos industriales y filtros de combustible Las llaves de vaso Snap-on\u00ae con sistema Flank Drive\u00ae sujetan la fijaci\u00f3n por los flancos\/planos, lo que proporciona un 15-25% [&hellip;]","og_url":"https:\/\/techmasterdemexico.com\/es\/producto\/juegos-de-servicio-diesel-4\/","og_site_name":"Techmaster de Mexico","article_modified_time":"2023-09-05T00:25:38+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/snap-on-FRHM19.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/techmasterdemexico.com\/en\/producto\/juegos-de-servicio-diesel-4\/","url":"https:\/\/techmasterdemexico.com\/en\/producto\/juegos-de-servicio-diesel-4\/","name":"Juegos de servicio diesel - Techmaster de Mexico","isPartOf":{"@id":"https:\/\/techmasterdemexico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/techmasterdemexico.com\/en\/producto\/juegos-de-servicio-diesel-4\/#primaryimage"},"image":{"@id":"https:\/\/techmasterdemexico.com\/en\/producto\/juegos-de-servicio-diesel-4\/#primaryimage"},"thumbnailUrl":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/snap-on-FRHM19.png","datePublished":"2021-10-11T19:30:09+00:00","dateModified":"2023-09-05T00:25:38+00:00","breadcrumb":{"@id":"https:\/\/techmasterdemexico.com\/en\/producto\/juegos-de-servicio-diesel-4\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/techmasterdemexico.com\/en\/producto\/juegos-de-servicio-diesel-4\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/techmasterdemexico.com\/en\/producto\/juegos-de-servicio-diesel-4\/#primaryimage","url":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/snap-on-FRHM19.png","contentUrl":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/snap-on-FRHM19.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/techmasterdemexico.com\/en\/producto\/juegos-de-servicio-diesel-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/techmasterdemexico.com\/es\/"},{"@type":"ListItem","position":2,"name":"Juegos de servicio diesel"}]},{"@type":"WebSite","@id":"https:\/\/techmasterdemexico.com\/es\/#website","url":"https:\/\/techmasterdemexico.com\/es\/","name":"Techmaster de Mexico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/techmasterdemexico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"}]}},"brands":[{"id":98,"name":"Snap On","slug":"snap-on"}],"_links":{"self":[{"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/product\/10008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/media\/20623"}],"wp:attachment":[{"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/media?parent=10008"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/pwb-brand?post=10008"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/product_brand?post=10008"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/product_cat?post=10008"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/es\/wp-json\/wp\/v2\/product_tag?post=10008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}