{"id":9967,"date":"2021-10-07T17:36:26","date_gmt":"2021-10-07T17:36:26","guid":{"rendered":"https:\/\/techmastermx.ddns.net\/producto\/taladros-rectos\/"},"modified":"2022-05-12T04:42:48","modified_gmt":"2022-05-12T04:42:48","slug":"taladros-rectos","status":"publish","type":"product","link":"https:\/\/techmasterdemexico.com\/en\/producto\/taladros-rectos\/","title":{"rendered":"Taladros rectos"},"content":{"rendered":"<ul>\n<li>Tama\u00f1o de entrada de aire: 1\/4&#8243; NPT<\/li>\n<li>Tama\u00f1o de manguera recomendado: 3\/8&#8243;<\/li>\n<li>Rendimiento nominal a una presi\u00f3n de aire de 90 psig (6,2 bar)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Reversibles y no reversibles<\/li>\n<li>Arranque por palanca<\/li>\n<li>Agarre de goma (1420, DR1422)<\/li>\n<\/ul>\n<p>Rendimiento:<\/p>\n<ul>\n<li>Potencia: 0,33 CV (0,25 kW) &#8211; 1 CV (0,75 kW)<\/li>\n<li>Rango de velocidad: 300 rpm &#8211; 21000 rpm<\/li>\n<li>Capacidad del portabrocas: 1\/4 &#8220;(6 mm) &#8211; 1\/2&#8221; (13 mm)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":10064,"template":"","meta":{"_acf_changed":false},"pwb-brand":[214],"product_brand":[],"product_cat":[366,47,50,261],"product_tag":[],"class_list":{"0":"post-9967","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-sioux","7":"product_cat-todos-los-productos","8":"product_cat-sioux","9":"product_cat-taladros","10":"product_cat-taladros-rectos","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taladros rectos - Techmaster de Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taladros rectos - Techmaster de Mexico\" \/>\n<meta property=\"og:description\" content=\"Reversibles y no reversibles  Arranque por palanca  Agarre de goma (1420, DR1422)  Rendimiento:   Potencia: 0,33 CV (0,25 kW) - 1 CV (0,75 kW)  Rango de velocidad: 300 rpm - 21000 rpm  Capacidad del portabrocas: 1\/4 &quot;(6 mm) - 1\/2&quot; (13 mm)  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/\" \/>\n<meta property=\"og:site_name\" content=\"Techmaster de Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-12T04:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/Sioux_Tools_1420_LF.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/taladros-rectos\\\/\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/taladros-rectos\\\/\",\"name\":\"Taladros rectos - Techmaster de Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/taladros-rectos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/taladros-rectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Sioux_Tools_1420_LF.png\",\"datePublished\":\"2021-10-07T17:36:26+00:00\",\"dateModified\":\"2022-05-12T04:42:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/taladros-rectos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/taladros-rectos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/taladros-rectos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Sioux_Tools_1420_LF.png\",\"contentUrl\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Sioux_Tools_1420_LF.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/taladros-rectos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/techmasterdemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taladros rectos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/\",\"name\":\"Techmaster de Mexico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/techmasterdemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taladros rectos - Techmaster de Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/","og_locale":"en_US","og_type":"article","og_title":"Taladros rectos - Techmaster de Mexico","og_description":"Reversibles y no reversibles  Arranque por palanca  Agarre de goma (1420, DR1422)  Rendimiento:   Potencia: 0,33 CV (0,25 kW) - 1 CV (0,75 kW)  Rango de velocidad: 300 rpm - 21000 rpm  Capacidad del portabrocas: 1\/4 \"(6 mm) - 1\/2\" (13 mm)  &nbsp;","og_url":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/","og_site_name":"Techmaster de Mexico","article_modified_time":"2022-05-12T04:42:48+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/Sioux_Tools_1420_LF.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/","url":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/","name":"Taladros rectos - Techmaster de Mexico","isPartOf":{"@id":"https:\/\/techmasterdemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/#primaryimage"},"image":{"@id":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/#primaryimage"},"thumbnailUrl":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/Sioux_Tools_1420_LF.png","datePublished":"2021-10-07T17:36:26+00:00","dateModified":"2022-05-12T04:42:48+00:00","breadcrumb":{"@id":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/#primaryimage","url":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/Sioux_Tools_1420_LF.png","contentUrl":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/Sioux_Tools_1420_LF.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/techmasterdemexico.com\/producto\/taladros-rectos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/techmasterdemexico.com\/"},{"@type":"ListItem","position":2,"name":"Taladros rectos"}]},{"@type":"WebSite","@id":"https:\/\/techmasterdemexico.com\/#website","url":"https:\/\/techmasterdemexico.com\/","name":"Techmaster de Mexico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/techmasterdemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"brands":[{"id":214,"name":"Sioux","slug":"sioux"}],"_links":{"self":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product\/9967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/media\/10064"}],"wp:attachment":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/media?parent=9967"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/pwb-brand?post=9967"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_brand?post=9967"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_cat?post=9967"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_tag?post=9967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}