{"id":8241,"date":"2021-08-19T18:30:55","date_gmt":"2021-08-19T18:30:55","guid":{"rendered":"http:\/\/techmastermx.ddns.net\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/"},"modified":"2021-12-28T22:26:13","modified_gmt":"2021-12-28T22:26:13","slug":"llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1","status":"publish","type":"product","link":"https:\/\/techmasterdemexico.com\/en\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/","title":{"rendered":"Llave de impacto de yunque largo para trabajo pesado de 1 \u201d"},"content":{"rendered":"<p>Llave de impacto de yunque largo para trabajo pesado de 1 &#8220;(rojo \/ negro)<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Dise\u00f1o liviano (16 lb)<\/li>\n<li>Potente salida de torsi\u00f3n de 1.800 ft-lb<\/li>\n<li>Avance de tres velocidades y retroceso a m\u00e1xima potencia<\/li>\n<li>Mango lateral ergon\u00f3mico acolchado para un uso c\u00f3modo<\/li>\n<li>Tope de goma para la nariz para mayor durabilidad de la herramienta y protecci\u00f3n de la pieza de trabajo<\/li>\n<li>Escape de direcci\u00f3n lateral (reversible) para un trabajo m\u00e1s limpio<\/li>\n<li>Mecanismo de impacto de doble martillo duradero y contundente<\/li>\n<\/ul>\n","protected":false},"featured_media":9434,"template":"","meta":{"_acf_changed":false},"pwb-brand":[98],"product_brand":[],"product_cat":[366,111,286,48],"product_tag":[],"class_list":{"0":"post-8241","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-snap-on","7":"product_cat-todos-los-productos","8":"product_cat-herramientas-electricas","9":"product_cat-herramientas-electricas-aire","10":"product_cat-snap-on","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Llave de impacto de yunque largo para trabajo pesado de 1 \u201d - Techmaster de Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Llave de impacto de yunque largo para trabajo pesado de 1 \u201d - Techmaster de Mexico\" \/>\n<meta property=\"og:description\" content=\"[:es]  Dise\u00f1o liviano (16 lb)  Potente salida de torsi\u00f3n de 1.800 ft-lb  Avance de tres velocidades y retroceso a m\u00e1xima potencia  Mango lateral ergon\u00f3mico acolchado para un uso c\u00f3modo  Tope de goma para la nariz para mayor durabilidad de la herramienta y protecci\u00f3n de la pieza de trabajo  Escape de direcci\u00f3n lateral (reversible) para un trabajo m\u00e1s limpio  Mecanismo de impacto de doble martillo duradero y contundente  [:en]    Dise\u00f1o liviano (16 lb)   Potente salida de torsi\u00f3n de 1.800 ft-lb   Avance de tres velocidades y retroceso a m\u00e1xima potencia   Mango lateral ergon\u00f3mico acolchado para un uso c\u00f3modo   Tope de goma para la nariz para mayor durabilidad de la herramienta y protecci\u00f3n de la pieza de trabajo   Escape de direcci\u00f3n lateral (reversible) para un trabajo m\u00e1s limpio   Mecanismo de impacto de doble martillo duradero y contundente   [:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Techmaster de Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-28T22:26:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/08\/PT1800AL.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\\\/\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\\\/\",\"name\":\"Llave de impacto de yunque largo para trabajo pesado de 1 \u201d - Techmaster de Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/PT1800AL.png\",\"datePublished\":\"2021-08-19T18:30:55+00:00\",\"dateModified\":\"2021-12-28T22:26:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/PT1800AL.png\",\"contentUrl\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/PT1800AL.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/techmasterdemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Llave de impacto de yunque largo para trabajo pesado de 1 \u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/\",\"name\":\"Techmaster de Mexico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/techmasterdemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Llave de impacto de yunque largo para trabajo pesado de 1 \u201d - Techmaster de Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/","og_locale":"en_US","og_type":"article","og_title":"Llave de impacto de yunque largo para trabajo pesado de 1 \u201d - Techmaster de Mexico","og_description":"[:es]  Dise\u00f1o liviano (16 lb)  Potente salida de torsi\u00f3n de 1.800 ft-lb  Avance de tres velocidades y retroceso a m\u00e1xima potencia  Mango lateral ergon\u00f3mico acolchado para un uso c\u00f3modo  Tope de goma para la nariz para mayor durabilidad de la herramienta y protecci\u00f3n de la pieza de trabajo  Escape de direcci\u00f3n lateral (reversible) para un trabajo m\u00e1s limpio  Mecanismo de impacto de doble martillo duradero y contundente  [:en]    Dise\u00f1o liviano (16 lb)   Potente salida de torsi\u00f3n de 1.800 ft-lb   Avance de tres velocidades y retroceso a m\u00e1xima potencia   Mango lateral ergon\u00f3mico acolchado para un uso c\u00f3modo   Tope de goma para la nariz para mayor durabilidad de la herramienta y protecci\u00f3n de la pieza de trabajo   Escape de direcci\u00f3n lateral (reversible) para un trabajo m\u00e1s limpio   Mecanismo de impacto de doble martillo duradero y contundente   [:]","og_url":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/","og_site_name":"Techmaster de Mexico","article_modified_time":"2021-12-28T22:26:13+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/08\/PT1800AL.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/","url":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/","name":"Llave de impacto de yunque largo para trabajo pesado de 1 \u201d - Techmaster de Mexico","isPartOf":{"@id":"https:\/\/techmasterdemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/#primaryimage"},"image":{"@id":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/#primaryimage"},"thumbnailUrl":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/08\/PT1800AL.png","datePublished":"2021-08-19T18:30:55+00:00","dateModified":"2021-12-28T22:26:13+00:00","breadcrumb":{"@id":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/#primaryimage","url":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/08\/PT1800AL.png","contentUrl":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/08\/PT1800AL.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/techmasterdemexico.com\/producto\/llave-de-impacto-de-yunque-largo-para-trabajo-pesado-de-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/techmasterdemexico.com\/"},{"@type":"ListItem","position":2,"name":"Llave de impacto de yunque largo para trabajo pesado de 1 \u201d"}]},{"@type":"WebSite","@id":"https:\/\/techmasterdemexico.com\/#website","url":"https:\/\/techmasterdemexico.com\/","name":"Techmaster de Mexico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/techmasterdemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"brands":[{"id":98,"name":"Snap On","slug":"snap-on"}],"_links":{"self":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product\/8241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/media\/9434"}],"wp:attachment":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/media?parent=8241"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/pwb-brand?post=8241"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_brand?post=8241"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_cat?post=8241"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_tag?post=8241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}