{"id":15114,"date":"2021-12-22T00:53:44","date_gmt":"2021-12-22T00:53:44","guid":{"rendered":"https:\/\/techmastermx.ddns.net\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/"},"modified":"2021-12-22T00:53:44","modified_gmt":"2021-12-22T00:53:44","slug":"micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set","status":"publish","type":"product","link":"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/","title":{"rendered":"Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"pwb-brand":[39],"product_brand":[],"product_cat":[366,331,414,417,38],"product_tag":[],"class_list":{"0":"post-15114","1":"product","2":"type-product","3":"status-publish","5":"pwb-brand-mitutoyo","6":"product_cat-todos-los-productos","7":"product_cat-instrumentos-de-medicion-y-gestion-de-datos","8":"product_cat-instrumentos-de-medicion-de-interiores","9":"product_cat-micrometros-de-interiores","10":"product_cat-mitutoyo","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set - Techmaster de Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set - Techmaster de Mexico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/\" \/>\n<meta property=\"og:site_name\" content=\"Techmaster de Mexico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\\\/\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\\\/\",\"name\":\"Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set - Techmaster de Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/#website\"},\"datePublished\":\"2021-12-22T00:53:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/en\\\/producto\\\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/techmasterdemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/\",\"name\":\"Techmaster de Mexico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/techmasterdemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set - Techmaster de Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/","og_locale":"en_US","og_type":"article","og_title":"Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set - Techmaster de Mexico","og_url":"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/","og_site_name":"Techmaster de Mexico","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/","url":"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/","name":"Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set - Techmaster de Mexico","isPartOf":{"@id":"https:\/\/techmasterdemexico.com\/#website"},"datePublished":"2021-12-22T00:53:44+00:00","breadcrumb":{"@id":"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/techmasterdemexico.com\/en\/producto\/micrometro-de-interiores-de-tres-contactos-holtest-en-juego-acero-templado-100-200mm-4-pcs-economy-set\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/techmasterdemexico.com\/"},{"@type":"ListItem","position":2,"name":"Micr\u00f3metro de interiores de tres contactos Holtest en juego (Acero templado) 100-200mm (4 pcs.), Economy Set"}]},{"@type":"WebSite","@id":"https:\/\/techmasterdemexico.com\/#website","url":"https:\/\/techmasterdemexico.com\/","name":"Techmaster de Mexico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/techmasterdemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"brands":[{"id":39,"name":"Mitutoyo","slug":"mitutoyo"}],"_links":{"self":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product\/15114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/media?parent=15114"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/pwb-brand?post=15114"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_brand?post=15114"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_cat?post=15114"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_tag?post=15114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}