{"id":10923,"date":"2021-10-29T19:10:03","date_gmt":"2021-10-29T19:10:03","guid":{"rendered":"https:\/\/techmastermx.ddns.net\/?post_type=product&#038;p=10923"},"modified":"2022-05-12T04:19:02","modified_gmt":"2022-05-12T04:19:02","slug":"remachadoras-de-compresion-6","status":"publish","type":"product","link":"https:\/\/techmasterdemexico.com\/en\/producto\/remachadoras-de-compresion-6\/","title":{"rendered":"Remachadoras de compresi\u00f3n"},"content":{"rendered":"<ul>\n<li>Tama\u00f1o de entrada de aire: 1\/4 &#8220;NPT<\/li>\n<li>Tama\u00f1o de manguera recomendado: 3\/8 &#8220;(10 mm)<\/li>\n<li>Rendimiento nominal a una presi\u00f3n de aire de 90 psig (6,2 bar)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Opciones de cilindro simple, t\u00e1ndem y triple<\/li>\n<li>Capacidad de remachado:<\/li>\n<li>1\/8 &#8220;(3 mm) (cilindro \u00fanico)<\/li>\n<li>3\/16 &#8220;(5 mm) (cilindro en t\u00e1ndem)<\/li>\n<li>1\/4 &#8220;(6 mm) (cilindro triple)<\/li>\n<li>Acelerador de seguridad<\/li>\n<\/ul>\n<p>Equipamiento estandar:<\/p>\n<ul>\n<li>Lista de partes<\/li>\n<li>Manual de instrucciones y seguridad<\/li>\n<li>Acci\u00f3n del acelerador de seguridad<\/li>\n<\/ul>\n","protected":false},"featured_media":10920,"template":"","meta":{"_acf_changed":false},"pwb-brand":[214],"product_brand":[],"product_cat":[366,245,248,47],"product_tag":[],"class_list":{"0":"post-10923","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-sioux","7":"product_cat-todos-los-productos","8":"product_cat-herramientas-especiales","9":"product_cat-remachadoras-de-compresion","10":"product_cat-sioux","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Remachadoras de compresi\u00f3n - Techmaster de Mexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remachadoras de compresi\u00f3n - Techmaster de Mexico\" \/>\n<meta property=\"og:description\" content=\"Opciones de cilindro simple, t\u00e1ndem y triple  Capacidad de remachado:  1\/8 &quot;(3 mm) (cilindro \u00fanico)  3\/16 &quot;(5 mm) (cilindro en t\u00e1ndem)  1\/4 &quot;(6 mm) (cilindro triple)  Acelerador de seguridad  Equipamiento estandar:   Lista de partes  Manual de instrucciones y seguridad  Acci\u00f3n del acelerador de seguridad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Techmaster de Mexico\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-12T04:19:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/SZEA6015-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/remachadoras-de-compresion-6\\\/\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/remachadoras-de-compresion-6\\\/\",\"name\":\"Remachadoras de compresi\u00f3n - Techmaster de Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/remachadoras-de-compresion-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/remachadoras-de-compresion-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/SZEA6015-.jpg\",\"datePublished\":\"2021-10-29T19:10:03+00:00\",\"dateModified\":\"2022-05-12T04:19:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/remachadoras-de-compresion-6\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/remachadoras-de-compresion-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/remachadoras-de-compresion-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/SZEA6015-.jpg\",\"contentUrl\":\"https:\\\/\\\/techmasterdemexico.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/SZEA6015-.jpg\",\"width\":650,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/producto\\\/remachadoras-de-compresion-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/techmasterdemexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Remachadoras de compresi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/techmasterdemexico.com\\\/#website\",\"url\":\"https:\\\/\\\/techmasterdemexico.com\\\/\",\"name\":\"Techmaster de Mexico\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/techmasterdemexico.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remachadoras de compresi\u00f3n - Techmaster de Mexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/","og_locale":"en_US","og_type":"article","og_title":"Remachadoras de compresi\u00f3n - Techmaster de Mexico","og_description":"Opciones de cilindro simple, t\u00e1ndem y triple  Capacidad de remachado:  1\/8 \"(3 mm) (cilindro \u00fanico)  3\/16 \"(5 mm) (cilindro en t\u00e1ndem)  1\/4 \"(6 mm) (cilindro triple)  Acelerador de seguridad  Equipamiento estandar:   Lista de partes  Manual de instrucciones y seguridad  Acci\u00f3n del acelerador de seguridad","og_url":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/","og_site_name":"Techmaster de Mexico","article_modified_time":"2022-05-12T04:19:02+00:00","og_image":[{"width":650,"height":650,"url":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/SZEA6015-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/","url":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/","name":"Remachadoras de compresi\u00f3n - Techmaster de Mexico","isPartOf":{"@id":"https:\/\/techmasterdemexico.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/#primaryimage"},"image":{"@id":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/#primaryimage"},"thumbnailUrl":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/SZEA6015-.jpg","datePublished":"2021-10-29T19:10:03+00:00","dateModified":"2022-05-12T04:19:02+00:00","breadcrumb":{"@id":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/#primaryimage","url":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/SZEA6015-.jpg","contentUrl":"https:\/\/techmasterdemexico.com\/wp-content\/uploads\/2021\/10\/SZEA6015-.jpg","width":650,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/techmasterdemexico.com\/producto\/remachadoras-de-compresion-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/techmasterdemexico.com\/"},{"@type":"ListItem","position":2,"name":"Remachadoras de compresi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/techmasterdemexico.com\/#website","url":"https:\/\/techmasterdemexico.com\/","name":"Techmaster de Mexico","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/techmasterdemexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"brands":[{"id":214,"name":"Sioux","slug":"sioux"}],"_links":{"self":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product\/10923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/media\/10920"}],"wp:attachment":[{"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/media?parent=10923"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/pwb-brand?post=10923"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_brand?post=10923"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_cat?post=10923"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/techmasterdemexico.com\/en\/wp-json\/wp\/v2\/product_tag?post=10923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}